{"id":1163,"date":"2022-02-07T22:32:11","date_gmt":"2022-02-08T01:32:11","guid":{"rendered":"https:\/\/psoul.com.br\/wiki\/?post_type=docs&#038;p=1163"},"modified":"2025-06-12T10:45:03","modified_gmt":"2025-06-12T13:45:03","password":"","slug":"sistema-de-tms-2","status":"publish","type":"docs","link":"https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/","title":{"rendered":"Sistema de TMs"},"content":{"rendered":"<p style=\"text-align: justify;\">O\u00a0<strong>sistema de TMs<\/strong> (technical machines) do PSoul segue o mesmo alinhamento do sistema de TMs dos jogos oficiais de Pok\u00e9mon. Cada uma das TMs \u00e9 respons\u00e1vel por ensinar um movimento diferente que normalmente o Pok\u00e9mon n\u00e3o possui no moveset &#8211; em alguns casos, o Pok\u00e9mon conter o movimento do TM na lista de egg moves ou at\u00e9 mesmo no moveset padr\u00e3o.<\/p>\n<p>As TMs s\u00e3o representadas por CDs, conforme mostra a imagem abaixo.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone wp-image-1164 size-full lazyload\" data-src=\"https:\/\/psoul.gg\/wiki\/wp-content\/uploads\/2022\/02\/1-13.png\" alt=\"\" width=\"142\" height=\"121\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 142px; --smush-placeholder-aspect-ratio: 142\/121;\" \/><noscript><img decoding=\"async\" class=\"alignnone wp-image-1164 size-full\" src=\"https:\/\/psoul.gg\/wiki\/wp-content\/uploads\/2022\/02\/1-13.png\" alt=\"\" width=\"142\" height=\"121\" \/><\/noscript><\/p>\n<p style=\"text-align: justify;\">Existem\u00a0<strong>tr\u00eas categorias<\/strong> distintas de TMs dispon\u00edveis no mundo do PSoul:<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>Heal<\/strong>, que normalmente s\u00e3o as que ensinam movimentos de cura ao Pok\u00e9mon, como as TMs Softboiled e Rest;<\/li>\n<li style=\"text-align: justify;\"><strong>Support<\/strong>, s\u00e3o as que ensinam movimentos de buff ou movimentos secund\u00e1rios que n\u00e3o necessariamente infligem dano, como as TMs Bulk Up, Calm Mind e Work Up;<\/li>\n<li style=\"text-align: justify;\"><strong>Offensive<\/strong>, que s\u00e3o as TMs de fato ofensivas, que ensinam movimentos que causam dano no advers\u00e1rio, como as TMs Fire Blast e Psychic.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>&#8211; Ensinando uma TM a um Pok\u00e9mon:<\/strong><\/p>\n<p style=\"text-align: justify;\">Cada Pok\u00e9mon pode aprender no m\u00e1ximo 2 TMs. Contudo, o Pok\u00e9mon n\u00e3o pode aprender 2 TMs que sejam da mesma categoria: offensive + offensive, heal + heal ou support + support. O Pok\u00e9mon somente aprende 2 TMs que sejam de categorias diferentes, como offensive + heal, offensive + support ou heal + support.<\/p>\n<p style=\"text-align: justify;\">Para ensinar um TM ao Pok\u00e9mon, basta clicar na TM e clicar na pok\u00e9bola do Pok\u00e9mon. Em seguida, uma janela ir\u00e1 aparecer na tela e o jogador ter\u00e1 que escolher qual movimento ser\u00e1 substitu\u00eddo pelo movimento que a TM ensinar\u00e1 ao Pok\u00e9mon.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone wp-image-1165 size-full lazyload\" data-src=\"https:\/\/psoul.gg\/wiki\/wp-content\/uploads\/2022\/02\/1-14.png\" alt=\"\" width=\"500\" height=\"98\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/98;\" \/><noscript><img decoding=\"async\" class=\"alignnone wp-image-1165 size-full\" src=\"https:\/\/psoul.gg\/wiki\/wp-content\/uploads\/2022\/02\/1-14.png\" alt=\"\" width=\"500\" height=\"98\" \/><\/noscript><\/p>\n<p style=\"text-align: justify;\">N\u00e3o se preocupe, \u00e9 poss\u00edvel alterar qual movimento ser\u00e1 substitu\u00eddo pela TM ap\u00f3s o Pok\u00e9mon j\u00e1 ter aprendido um movimento por uma TM. Em outras palavras, \u00e9 poss\u00edvel mover o movimento ensinado pela TM de lugar. Para isso, basta ir ao Trade Center e encontrar com o\u00a0<strong>NPC Curt Raeburn<\/strong>.<\/p>\n<p style=\"text-align: center;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-1166 size-full\" src=\"https:\/\/psoul.gg\/wiki\/wp-content\/uploads\/2022\/02\/1-15.png\" alt=\"\" width=\"691\" height=\"509\" \/><\/p>\n<p>Para trocar o movimento da TM de lugar, fale com o NPC:<\/p>\n<p><strong>&#8211; Chocolate<\/strong>: Oi<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Curt Raeburn<\/strong>: Ol\u00e1 Chocolate. Voc\u00ea quer <strong>trocar<\/strong> technichal Machines? Aqui voc\u00ea tamb\u00e9m pode <strong>remover<\/strong> ou <strong>mover<\/strong> o movimento de TM do seu Pokemon!<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Chocolate<\/strong>: mover<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Curt Raeburn<\/strong>: Sim, eu posso mudar o movimento que o seu Pokemon esqueceu para aprender o movimento do TM. Qual slot voc\u00ea quer mudar? <strong>1<\/strong> ou <strong>2<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Chocolate<\/strong>: ? (<em>escolha a TM que deseja mudar de lugar<\/em>)<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Curt Raeburn<\/strong>: Ok, agora qual \u00e9 o movimento do seu Pokemon que voc\u00ea deseja substituir com o TM? Escreva o nome exato!<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Chocolate<\/strong>: ? (<em>escreva <strong>exatamente<\/strong> o nome que deseja substituir pelo TM, incluindo letras mai\u00fasculas<\/em>)<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Curt Raeburn<\/strong>: Voc\u00ea realmente deseja mover o movimento da TM de seu <em>Pok\u00e9mon<\/em> para substituir o movimento <em>?????<\/em>?<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Chocolate<\/strong>: yes<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Curt Raeburn<\/strong>: Done!<\/p>\n<p>Feito! Agora o Pok\u00e9mon voltou a aprender o movimento anterior e substituiu o movimento novo pela TM.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>&#8211; Removendo TM de um Pok\u00e9mon:<\/strong><\/p>\n<p style=\"text-align: justify;\">Para remover a TM de um Pok\u00e9mon, basta ir ao mesmo NPC mostrado anteriormente e come\u00e7ar o di\u00e1logo de &#8220;remo\u00e7\u00e3o&#8221;, como:\u00a0<strong>oi<\/strong>, <strong>remover<\/strong>. Com isso, o NPC ir\u00e1 perguntar se o jogador quer remover a TM 1 ou a TM 2. Em seguida, \u00e9 s\u00f3 o jogador escolher a TM e confirmar, mas com aten\u00e7\u00e3o: <strong>as TMs que n\u00e3o s\u00e3o <em>reusables<\/em> n\u00e3o retornam para a backpack ao serem removidas, logo, ao se remover uma TM que n\u00e3o se qualifica como <em>reusable<\/em>, o jogador perde a TM<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>&#8211; Vendendo TMs ao NPC:<\/strong><\/p>\n<p style=\"text-align: justify;\">Para vender uma TM ao NPC, basta ir ao mesmo NPC mostrado anteriormente e come\u00e7ar o di\u00e1logo de &#8220;troca&#8221;, como:\u00a0<strong>oi<\/strong>,\u00a0<strong>trocar<\/strong>. Assim, abrir\u00e1 uma lista de TMs que o jogador possui e que pode vender ao NPC pelo pre\u00e7o fixo mostrado no <em>look<\/em> da TM.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O\u00a0sistema de TMs (technical machines) do PSoul segue o mesmo alinhamento do sistema de TMs dos jogos oficiais de Pok\u00e9mon. Cada uma das TMs \u00e9 respons\u00e1vel por ensinar um movimento diferente que normalmente o Pok\u00e9mon n\u00e3o possui no moveset &#8211; em alguns casos, o Pok\u00e9mon conter o movimento do TM na lista de egg moves [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_eb_attr":"","footnotes":""},"doc_category":[35],"glossaries":[],"doc_tag":[],"class_list":["post-1163","docs","type-docs","status-publish","hentry","doc_category-sistemas"],"year_month":"2026-09","word_count":640,"total_views":"3393","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"lovinsfps","author_nicename":"lovinsfps","author_url":"https:\/\/psoul.gg\/wiki\/author\/lovinsfps\/"},"doc_category_info":[{"term_name":"Sistemas","term_url":"https:\/\/psoul.gg\/wiki\/guide-category\/sistemas\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sistema de TMs - PSoul Wiki<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sistema de TMs - PSoul Wiki\" \/>\n<meta property=\"og:description\" content=\"O\u00a0sistema de TMs (technical machines) do PSoul segue o mesmo alinhamento do sistema de TMs dos jogos oficiais de Pok\u00e9mon. Cada uma das TMs \u00e9 respons\u00e1vel por ensinar um movimento diferente que normalmente o Pok\u00e9mon n\u00e3o possui no moveset &#8211; em alguns casos, o Pok\u00e9mon conter o movimento do TM na lista de egg moves [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/\" \/>\n<meta property=\"og:site_name\" content=\"PSoul Wiki\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/psoul\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-12T13:45:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/psoul.gg\/wiki\/wp-content\/uploads\/2023\/02\/logo.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"474\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/\",\"url\":\"https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/\",\"name\":\"Sistema de TMs - PSoul Wiki\",\"isPartOf\":{\"@id\":\"https:\/\/psoul.gg\/wiki\/pt\/psoul-wiki-portugues\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/psoul.gg\/wiki\/wp-content\/uploads\/2022\/02\/1-13.png\",\"datePublished\":\"2022-02-08T01:32:11+00:00\",\"dateModified\":\"2025-06-12T13:45:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/#primaryimage\",\"url\":\"https:\/\/psoul.gg\/wiki\/wp-content\/uploads\/2022\/02\/1-13.png\",\"contentUrl\":\"https:\/\/psoul.gg\/wiki\/wp-content\/uploads\/2022\/02\/1-13.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/psoul.gg\/wiki\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sistema de TMs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/psoul.gg\/wiki\/pt\/psoul-wiki-portugues\/#website\",\"url\":\"https:\/\/psoul.gg\/wiki\/pt\/psoul-wiki-portugues\/\",\"name\":\"PSoul Wiki\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/psoul.gg\/wiki\/pt\/psoul-wiki-portugues\/#organization\"},\"alternateName\":\"PSoul\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/psoul.gg\/wiki\/pt\/psoul-wiki-portugues\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/psoul.gg\/wiki\/pt\/psoul-wiki-portugues\/#organization\",\"name\":\"PSoul Wiki\",\"url\":\"https:\/\/psoul.gg\/wiki\/pt\/psoul-wiki-portugues\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/psoul.gg\/wiki\/pt\/psoul-wiki-portugues\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/psoul.gg\/wiki\/wp-content\/uploads\/2023\/02\/logo.webp\",\"contentUrl\":\"https:\/\/psoul.gg\/wiki\/wp-content\/uploads\/2023\/02\/logo.webp\",\"width\":474,\"height\":120,\"caption\":\"PSoul Wiki\"},\"image\":{\"@id\":\"https:\/\/psoul.gg\/wiki\/pt\/psoul-wiki-portugues\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/psoul\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sistema de TMs - PSoul Wiki","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Sistema de TMs - PSoul Wiki","og_description":"O\u00a0sistema de TMs (technical machines) do PSoul segue o mesmo alinhamento do sistema de TMs dos jogos oficiais de Pok\u00e9mon. Cada uma das TMs \u00e9 respons\u00e1vel por ensinar um movimento diferente que normalmente o Pok\u00e9mon n\u00e3o possui no moveset &#8211; em alguns casos, o Pok\u00e9mon conter o movimento do TM na lista de egg moves [&hellip;]","og_url":"https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/","og_site_name":"PSoul Wiki","article_publisher":"https:\/\/facebook.com\/psoul","article_modified_time":"2025-06-12T13:45:03+00:00","og_image":[{"width":474,"height":120,"url":"https:\/\/psoul.gg\/wiki\/wp-content\/uploads\/2023\/02\/logo.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/","url":"https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/","name":"Sistema de TMs - PSoul Wiki","isPartOf":{"@id":"https:\/\/psoul.gg\/wiki\/pt\/psoul-wiki-portugues\/#website"},"primaryImageOfPage":{"@id":"https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/#primaryimage"},"image":{"@id":"https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/#primaryimage"},"thumbnailUrl":"https:\/\/psoul.gg\/wiki\/wp-content\/uploads\/2022\/02\/1-13.png","datePublished":"2022-02-08T01:32:11+00:00","dateModified":"2025-06-12T13:45:03+00:00","breadcrumb":{"@id":"https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/#primaryimage","url":"https:\/\/psoul.gg\/wiki\/wp-content\/uploads\/2022\/02\/1-13.png","contentUrl":"https:\/\/psoul.gg\/wiki\/wp-content\/uploads\/2022\/02\/1-13.png"},{"@type":"BreadcrumbList","@id":"https:\/\/psoul.gg\/wiki\/guides\/sistema-de-tms-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/psoul.gg\/wiki\/"},{"@type":"ListItem","position":2,"name":"Sistema de TMs"}]},{"@type":"WebSite","@id":"https:\/\/psoul.gg\/wiki\/pt\/psoul-wiki-portugues\/#website","url":"https:\/\/psoul.gg\/wiki\/pt\/psoul-wiki-portugues\/","name":"PSoul Wiki","description":"","publisher":{"@id":"https:\/\/psoul.gg\/wiki\/pt\/psoul-wiki-portugues\/#organization"},"alternateName":"PSoul","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/psoul.gg\/wiki\/pt\/psoul-wiki-portugues\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/psoul.gg\/wiki\/pt\/psoul-wiki-portugues\/#organization","name":"PSoul Wiki","url":"https:\/\/psoul.gg\/wiki\/pt\/psoul-wiki-portugues\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/psoul.gg\/wiki\/pt\/psoul-wiki-portugues\/#\/schema\/logo\/image\/","url":"https:\/\/psoul.gg\/wiki\/wp-content\/uploads\/2023\/02\/logo.webp","contentUrl":"https:\/\/psoul.gg\/wiki\/wp-content\/uploads\/2023\/02\/logo.webp","width":474,"height":120,"caption":"PSoul Wiki"},"image":{"@id":"https:\/\/psoul.gg\/wiki\/pt\/psoul-wiki-portugues\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/psoul"]}]}},"_links":{"self":[{"href":"https:\/\/psoul.gg\/wiki\/wp-json\/wp\/v2\/docs\/1163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/psoul.gg\/wiki\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/psoul.gg\/wiki\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/psoul.gg\/wiki\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/psoul.gg\/wiki\/wp-json\/wp\/v2\/comments?post=1163"}],"version-history":[{"count":1,"href":"https:\/\/psoul.gg\/wiki\/wp-json\/wp\/v2\/docs\/1163\/revisions"}],"predecessor-version":[{"id":3492,"href":"https:\/\/psoul.gg\/wiki\/wp-json\/wp\/v2\/docs\/1163\/revisions\/3492"}],"wp:attachment":[{"href":"https:\/\/psoul.gg\/wiki\/wp-json\/wp\/v2\/media?parent=1163"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/psoul.gg\/wiki\/wp-json\/wp\/v2\/doc_category?post=1163"},{"taxonomy":"glossaries","embeddable":true,"href":"https:\/\/psoul.gg\/wiki\/wp-json\/wp\/v2\/glossaries?post=1163"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/psoul.gg\/wiki\/wp-json\/wp\/v2\/doc_tag?post=1163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}